{"id":4165,"date":"2018-05-06T17:23:53","date_gmt":"2018-05-06T16:23:53","guid":{"rendered":"http:\/\/la-licorne-a-lunettes.fr\/?p=4165"},"modified":"2018-05-06T17:25:05","modified_gmt":"2018-05-06T16:25:05","slug":"ce-geant-mon-ami","status":"publish","type":"post","link":"https:\/\/la-licorne-a-lunettes.fr\/index.php\/2018\/05\/06\/ce-geant-mon-ami\/","title":{"rendered":"Ce g\u00e9ant mon ami"},"content":{"rendered":"<figure id=\"attachment_4185\" aria-describedby=\"caption-attachment-4185\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" class=\"size-medium wp-image-4185\" src=\"http:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/Ce-ge\u0301ant-mon-ami-couv-550x550-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/Ce-ge\u0301ant-mon-ami-couv-550x550-300x300.jpg 300w, https:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/Ce-ge\u0301ant-mon-ami-couv-550x550-150x150.jpg 150w, https:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/Ce-ge\u0301ant-mon-ami-couv-550x550-100x100.jpg 100w, https:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/Ce-ge\u0301ant-mon-ami-couv-550x550-200x200.jpg 200w, https:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/Ce-ge\u0301ant-mon-ami-couv-550x550.jpg 550w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-4185\" class=\"wp-caption-text\">(c) Maison Eliza<\/figcaption><\/figure>\n<p>Ahhh je l&rsquo;attendais depuis longtemps la rencontre avec cette petite Luna et ce g\u00e9ant ! Un grand coup de coeur pour cet album tout en tendresse et tons pastel.<\/p>\n<p>La couverture est magnifique, le contraste entre la petite puce et son immense ami donne envie d&rsquo;en savoir plus : une relation d&rsquo;amiti\u00e9 sp\u00e9ciale qu&rsquo;on a envie de d\u00e9couvrir.<\/p>\n<p>Luna a un meilleur ami donc, un peu particulier. \u00ab\u00a0C&rsquo;est un g\u00e9ant, un vrai de vrai de vrai.\u00a0\u00bb Et pourquoi pas ! Ils passent leur temps libre ensemble, du matin au soir : dans la paume de sa main ou pos\u00e9e sur son \u00e9paule, Luna voyage en voyant le monde d&rsquo;un autre point de vue, prot\u00e9g\u00e9e par son confident.<\/p>\n<p>Cet ami est unique, tr\u00e8s pr\u00e9cieux pour la jeune Luna. Est-ce le fruit de son imagination ? Va savoir&#8230; \ud83d\ude09 L&rsquo;important est que cet alter \u00e9go est l\u00e0 pour elle, pour le premier bonjour du matin et le dernier bonsoir avant de s&rsquo;endormir.<\/p>\n<p>Mais un jour,&nbsp;il dispara\u00eet&#8230; Et Luna d\u00e9sesp\u00e8re de ne plus avoir de ses nouvelles. Une lettre va la conduire \u00e0 se mettre \u00e0 sa recherche&#8230; Vont-ils se retrouver ?<\/p>\n<p><!--more--><\/p>\n<figure id=\"attachment_4183\" aria-describedby=\"caption-attachment-4183\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-4183 size-full\" src=\"http:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/Ce-geant-mon-ami_extrait1-2.jpg\" alt=\"\" width=\"550\" height=\"344\" srcset=\"https:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/Ce-geant-mon-ami_extrait1-2.jpg 550w, https:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/Ce-geant-mon-ami_extrait1-2-300x188.jpg 300w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><figcaption id=\"caption-attachment-4183\" class=\"wp-caption-text\">(c) Maison Eliza<\/figcaption><\/figure>\n<p>Pour cela, cher lecteur, ch\u00e8re lectrice, tu vas devoir aller acheter ce magnifique album, car je suis une coquine de licorne et je ne te raconterai pas la fin (ouhhh que je suis fourbe, niark niark).<\/p>\n<div class=\"text_exposed_show\">\n<p><img loading=\"lazy\" class=\"alignleft size-medium wp-image-4188\" src=\"http:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/ce-geant-mon-ami-inter-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/ce-geant-mon-ami-inter-225x300.jpg 225w, https:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/ce-geant-mon-ami-inter.jpg 720w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>Une belle histoire d&rsquo;amiti\u00e9 et d&rsquo;espoir tout en po\u00e9sie. Une respiration n\u00e9cessaire dans le monde de brute dans lequel on vit, \u00e0 lire seul ou accompagn\u00e9.<\/p>\n<p>L&rsquo;univers graphique de Lili la Baleine est d\u00e9licieux, et il accompagne parfaitement la po\u00e9sie des mots d&rsquo;Ingrid Chabbert.<\/p>\n<p>Tout est en suggestion, convoquant l&rsquo;imaginaire du lecteur, l&rsquo;invitant \u00e0 voyager dans le monde onirique\/r\u00e9\u00e9l de Luna. Les teintes de bleu et de vert cr\u00e9ent une ambiance aquatique tr\u00e8s riche dont la barrette \u00e9toile de mer de Luna apparait comme un clin d&rsquo;oeil.<\/p>\n<\/div>\n<figure id=\"attachment_4184\" aria-describedby=\"caption-attachment-4184\" style=\"width: 300px\" class=\"wp-caption alignright\"><img loading=\"lazy\" class=\"size-medium wp-image-4184\" src=\"http:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/ce-ge\u0301ant-mon-ami-550x550-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/ce-ge\u0301ant-mon-ami-550x550-300x300.jpg 300w, https:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/ce-ge\u0301ant-mon-ami-550x550-150x150.jpg 150w, https:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/ce-ge\u0301ant-mon-ami-550x550-100x100.jpg 100w, https:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/ce-ge\u0301ant-mon-ami-550x550-200x200.jpg 200w, https:\/\/la-licorne-a-lunettes.fr\/wp-content\/uploads\/2018\/05\/ce-ge\u0301ant-mon-ami-550x550.jpg 550w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-4184\" class=\"wp-caption-text\">(c) Maison Eliz<\/figcaption><\/figure>\n<p>C\u00f4t\u00e9 format, il faut souligner la qualit\u00e9 de la fabrication : cet album est un bel objet, adapt\u00e9 aux plus petits pour la manipulation. L&rsquo;impression soign\u00e9e valorise les couleurs subtiles des illustrations, ce qui participe \u00e0 v\u00e9hiculer toute l&rsquo;\u00e9motion du r\u00e9cit.<\/p>\n<p>Bonus pour ceux qui seront les plus attentifs, Lili la baleine a \u00e9grain\u00e9 quelques personnages dans les second plans pour susciter la curiosit\u00e9 des lecteurs et \u00e9veiller leur imaginaire : un lapin qui fait de la plong\u00e9e sous-marine, une pieuvre qui lit Jules Verne, une tasse g\u00e9ante aquarium, un pot \u00e0 champignon ou un arrosoir \u00e0 th\u00e9&#8230; A lire et \u00e0 relire donc pour le plaisir de les d\u00e9couvrir !<\/p>\n<p>Et pour mieux comprendre les diff\u00e9rentes \u00e9tapes de la naissance de cet album, <a href=\"http:\/\/maisoneliza.com\/histoire-dun-livre-chez-maison-eliza\/\" target=\"_blank\" rel=\"noopener\">c&rsquo;est par ici<\/a>, une belle id\u00e9e de l&rsquo;\u00e9diteur Maison Eliza pour entrer dans les coulisses de la cr\u00e9ation.<\/p>\n<p><strong>Autrice : <a href=\"https:\/\/www.facebook.com\/Ingrid-Chabbert-673042596049509\/?ref=bookmarks\" target=\"_blank\" rel=\"noopener\">Ingrid CHABBERT<\/a><\/strong><br \/>\n<strong> Illustratrice : <a href=\"http:\/\/www.lililabaleineverte.fr\/2018\/ce-geant-mon-ami\/\" target=\"_blank\" rel=\"noopener\">Lili la BALEINE<\/a><\/strong><br \/>\n<strong> Edition : <a href=\"http:\/\/maisoneliza.com\/boutique\/ce-geant-mon-ami\/\" target=\"_blank\" rel=\"noopener\">Maison Eliza<\/a> &#8211; Album &#8211; Collection Pistache &#8211; 32 pages &#8211; 14,90euros<\/strong><br \/>\n<strong> Ann\u00e9e : Avril 2018&nbsp;<\/strong><\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>De la m\u00eame autrice (non exhaustif), derni\u00e8res parutions :&nbsp;<br \/>\n&#8211; 5 mouches et une trompette (album) (<a href=\"http:\/\/la-licorne-a-lunettes.fr\/index.php\/2016\/11\/03\/5-mouches-et-une-trompette\/\" target=\"_blank\" rel=\"noopener\">chroniqu\u00e9 ici<\/a>)<br \/>\n&#8211; Moi, Albert d\u00e9testateur de livre (album) (<a href=\"http:\/\/la-licorne-a-lunettes.fr\/index.php\/2017\/01\/03\/moi-albert-detestateur-de-livres\/\" target=\"_blank\" rel=\"noopener\">chroniqu\u00e9 ici<\/a>)<br \/>\n&#8211; Kadogo (album) (<a href=\"http:\/\/la-licorne-a-lunettes.fr\/index.php\/2017\/04\/02\/kadogo\/\" target=\"_blank\" rel=\"noopener\">chroniqu\u00e9 ici<\/a>)<br \/>\n&#8211; Fais passer ! (album) (<a href=\"http:\/\/la-licorne-a-lunettes.fr\/index.php\/2016\/11\/29\/fais-passer\/\" target=\"_blank\" rel=\"noopener\">chroniqu\u00e9 ici<\/a>)<br \/>\n&#8211; Le chaudron magique (premi\u00e8re lecture)<br \/>\n&#8211; Ecumes (roman graphique) (<a href=\"http:\/\/la-licorne-a-lunettes.fr\/index.php\/2017\/03\/05\/ecumes\/\" target=\"_blank\" rel=\"noopener\">chroniqu\u00e9 ici<\/a>)<br \/>\n&#8211; Un m\u00e8re \u00e0 Brooklyn (roman) (<a href=\"http:\/\/la-licorne-a-lunettes.fr\/index.php\/2017\/04\/06\/une-mere-a-brooklyn\/\" target=\"_blank\" rel=\"noopener\">chroniqu\u00e9 ici<\/a>)<br \/>\n\u2013 Tine et Junior (BD)<br \/>\n\u2013 Poils aux pattes<br \/>\n\u2013 Si tu ne ranges pas ta chambre<br \/>\n\u2013 La revanche des chaussettes qui puent<br \/>\n\u2013 Tout le monde sait faire du v\u00e9lo<br \/>\n\u2013 L\u2019imagier des saisons<br \/>\n\u2013 Les jumelles<br \/>\n\u2013 Artus et Lubin<br \/>\n\u2013 Y a un monstre \u00e0 c\u00f4t\u00e9<br \/>\n\u2013 La tisseuse de nuages<br \/>\n&#8211; La S\u00e9rie des Dinos aec Anne Loyer<\/p>\n<p>Chez Des ronds dans l\u2019O :<\/p>\n<ul>\n<li><a class=\"texte\" href=\"https:\/\/www.desrondsdanslo.com\/Malo.html\">Le bateau de Malo<\/a>, illustr\u00e9 par Fabiana Attanasio<\/li>\n<li><a class=\"texte\" href=\"https:\/\/www.desrondsdanslo.com\/MemoireAuxOiseaux.html\">La m\u00e9moire aux oiseaux<\/a>, illustr\u00e9 par Soufie<\/li>\n<li><a class=\"texte\" href=\"https:\/\/www.desrondsdanslo.com\/Tisseuse.html\">La tisseuse de nuages<\/a>, illustr\u00e9 par Virginie Rapiat<\/li>\n<li><a class=\"texte\" href=\"https:\/\/www.desrondsdanslo.com\/LePetitGilet.html\">Le petit gilet beige<\/a>, illustr\u00e9 par Marie Lafrance<\/li>\n<li><a class=\"texte\" href=\"https:\/\/www.desrondsdanslo.com\/LeLivreDeMaman.html\">Le livre de maman<\/a>, illustr\u00e9 par C\u00e9cile Bondon<\/li>\n<li><a class=\"texte\" href=\"https:\/\/www.desrondsdanslo.com\/MonPepe.html\">Mon p\u00e9p\u00e9<\/a>, illustr\u00e9 par Annette Boisnard<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>De la m\u00eame illustratrice (non exaustif) :&nbsp;<br \/>\n&#8211; Un lion tr\u00e8s coquet avec&nbsp;Val\u00e9rie Weishar-Giuliani &#8211; Maison Eliza<br \/>\n&#8211; La s\u00e9rie \u00ab\u00a0Ben\u00a0\u00bb avec&nbsp;Francesca et Romain Sardou chez&nbsp;<a href=\"http:\/\/hachette-jeunesse.com\/ben\" target=\"_blank\" rel=\"noopener\">Hachette jeunesse<br \/>\n<\/a>&#8211; La part du singe avec Pog chez&nbsp;<a href=\"http:\/\/www.editions-bilboquet.com\/la-part-du-singe.php?page=&amp;cat=1&amp;scat=&amp;sscat=&amp;order=1\" target=\"_blank\" rel=\"noopener\">Bilboquet<br \/>\n<\/a><span style=\"line-height: 1.5;\">&#8211;&nbsp;<\/span><span style=\"line-height: 1.5;\">Mamie est partie&nbsp;<\/span><span style=\"line-height: 1.5;\">avec Pog chez&nbsp;<\/span><a style=\"line-height: 1.5;\" href=\"http:\/\/www.gautier-languereau.fr\/auteur\/lili-la-baleine\" target=\"_blank\" rel=\"noopener\">Gautier-Languereau<br \/>\n<\/a>&#8211;&nbsp;Comment profiter de ses vacances quand on est un dragon ?avec&nbsp;Veronique Cauchy chez&nbsp;<a href=\"http:\/\/www.lililabaleineverte.fr\/parutions\/\" target=\"_blank\" rel=\"noopener\">Larousse<\/a><br \/>\n&#8211; Comment reconnaitre les dragons ? avec&nbsp;Veronique Cauchy chez&nbsp;<a href=\"http:\/\/www.lililabaleineverte.fr\/parutions\/\" target=\"_blank\" rel=\"noopener\">Larousse<br \/>\n<\/a>&#8211;&nbsp;Exp\u00e9dition Gropipi&nbsp;avec Didier Levy chez&nbsp;<a href=\"http:\/\/www.lililabaleineverte.fr\/parutions\/\" target=\"_blank\" rel=\"noopener\">Gautier-Languereau<br \/>\n<\/a>&#8211;&nbsp;M\u00eame pas peur ! avec Pog chez&nbsp;<a href=\"http:\/\/www.editionslito.com\/\" target=\"_blank\" rel=\"noopener\">Lito<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ahhh je l&rsquo;attendais depuis longtemps la rencontre avec cette petite Luna et ce g\u00e9ant ! Un grand coup de coeur pour cet album tout en tendresse et tons pastel. La couverture est magnifique, le contraste entre la petite puce et son immense ami donne envie d&rsquo;en savoir plus : une relation d&rsquo;amiti\u00e9 sp\u00e9ciale qu&rsquo;on a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[17,45,61],"tags":[52,7,252,87,312],"_links":{"self":[{"href":"https:\/\/la-licorne-a-lunettes.fr\/index.php\/wp-json\/wp\/v2\/posts\/4165"}],"collection":[{"href":"https:\/\/la-licorne-a-lunettes.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/la-licorne-a-lunettes.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/la-licorne-a-lunettes.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/la-licorne-a-lunettes.fr\/index.php\/wp-json\/wp\/v2\/comments?post=4165"}],"version-history":[{"count":11,"href":"https:\/\/la-licorne-a-lunettes.fr\/index.php\/wp-json\/wp\/v2\/posts\/4165\/revisions"}],"predecessor-version":[{"id":4192,"href":"https:\/\/la-licorne-a-lunettes.fr\/index.php\/wp-json\/wp\/v2\/posts\/4165\/revisions\/4192"}],"wp:attachment":[{"href":"https:\/\/la-licorne-a-lunettes.fr\/index.php\/wp-json\/wp\/v2\/media?parent=4165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/la-licorne-a-lunettes.fr\/index.php\/wp-json\/wp\/v2\/categories?post=4165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/la-licorne-a-lunettes.fr\/index.php\/wp-json\/wp\/v2\/tags?post=4165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}